{"id":1849,"date":"2023-06-13T18:18:19","date_gmt":"2023-06-13T16:18:19","guid":{"rendered":"https:\/\/biarritz.wordcamp.org\/2023\/?post_type=wcb_sponsor&#038;p=1849"},"modified":"2023-06-13T18:18:20","modified_gmt":"2023-06-13T16:18:20","slug":"newwwave","status":"publish","type":"wcb_sponsor","link":"https:\/\/biarritz.wordcamp.org\/2023\/sponsor\/newwwave\/","title":{"rendered":"Newwwave"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Prenez la nouvelle vague pour vos projets web !<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Chez <strong>Newwwave<\/strong>, on\u00a0adore concevoir des sites web sur mesure avec WordPress. Pourquoi\u2009? Parce que nous sommes des passionn\u00e9s, des perfectionnistes et des amoureux du travail utile et bien fait. Parce que pour nous, les templates impersonnels que l\u2019on trouve sur le web servent le plus grand nombre et personne \u00e0 la fois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre c\u0153ur de m\u00e9tier est de vous proposer des sites web 100 % sur mesure avec WordPress qui vous correspondent.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un site web, c\u2019est comme Rome,&nbsp;\u00e7a ne se construit pas en un jour.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il faut du temps et de la r\u00e9flexion. Des comp\u00e9tences strat\u00e9giques, techniques, esth\u00e9tiques et r\u00e9dactionnelles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre r\u00f4le chez Newwwave est de vous proposer un service 100 % sur mesure avec un accompagnement humain, pour vous offrir un site internet qui sortira du lot, gr\u00e2ce \u00e0 sa fiabilit\u00e9 technique, son design et son contenu \u00e0 l\u2019image de vos besoins et de vos objectifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fini de ramer !<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Passez-nous voir \u00e0 notre stand pendant le WordCamp ou contactez-nous sur&nbsp;<a href=\"http:\/\/newwwave.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">newwwave.com<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous r\u00e9pondrons avec plaisir \u00e0 vos questions et vous accompagnerons dans vos projets web !<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-8f98fe35 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/newwwave.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Decouvrir l&rsquo;Agence Newwwave<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prenez la nouvelle vague pour vos projets web ! Chez Newwwave, on\u00a0adore concevoir des sites web sur mesure avec WordPress. Pourquoi\u2009? Parce que nous sommes des passionn\u00e9s, des perfectionnistes et des amoureux du travail utile et bien fait. Parce que pour nous, les templates impersonnels que l\u2019on trouve sur le web servent le plus grand [&hellip;]<\/p>\n","protected":false},"featured_media":1893,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_wcpt_sponsor_website":"https:\/\/newwwave.com\/","footnotes":""},"sponsor_level":[22],"class_list":["post-1849","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-princier"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peI5BS-tP","_links":{"self":[{"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/sponsors\/1849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":2,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/sponsors\/1849\/revisions"}],"predecessor-version":[{"id":1892,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/sponsors\/1849\/revisions\/1892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/media\/1893"}],"wp:attachment":[{"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/media?parent=1849"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/sponsor_level?post=1849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}