{"id":2267,"date":"2023-07-05T10:21:23","date_gmt":"2023-07-05T08:21:23","guid":{"rendered":"https:\/\/biarritz.wordcamp.org\/2023\/?post_type=wcb_session&#038;p=2267"},"modified":"2023-08-03T11:45:02","modified_gmt":"2023-08-03T09:45:02","slug":"optimiser-votre-conversion-e-commerce","status":"publish","type":"wcb_session","link":"https:\/\/biarritz.wordcamp.org\/2023\/session\/optimiser-votre-conversion-e-commerce\/","title":{"rendered":"Un site qui g\u00e9n\u00e8re plus de leads ou clients ? Pensez #AvantPendantApr\u00e8s !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vous managez un site WordPress ecommerce ou g\u00e9n\u00e9rateur de lead ? Fort bien &#8230; Et combien de temps avez-vous consacr\u00e9, ce trimestre, \u00e0 l&rsquo;am\u00e9lioration de la conversion de votre site ? &#8230;&nbsp;\ud83d\ude33&nbsp;&#8230; Ok &#8230;&nbsp; On s&rsquo;en doutait &#8230; On en reparle plus bas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La conversion sur un site, \u00e7a ne se r\u00eave pas,&nbsp; \u00e7a ne s&rsquo;esp\u00e8re pas, \u00e7a ne se d\u00e9cr\u00e8te pas, \u00e7a s&rsquo;organise. Fa\u00e7on puzzle&nbsp;\ud83e\udde9&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une piste pour vous mettre sur la voie : la conversion c&rsquo;est beaucoup d&rsquo; \u00ab\u00a0Avant\u00a0\u00bb, beaucoup de \u00ab\u00a0Pendant\u00a0\u00bb et une bonne dose \u00ab\u00a0d&rsquo;Apr\u00e8s\u00a0\u00bb&#8230;. ? &#8230; !!!!! Un Apr\u00e8s qui devient m\u00eame un Avant si vous faites ce qu&rsquo;il faut. Vous suivez ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un peu myst\u00e9rieux tout \u00e7a &#8230; Pourtant am\u00e9liorer sa conversion et son chiffre d&rsquo;affaires, \u00e7a commence par beaucoup de bon sens, en se posant les bonnes questions &#8230; pour \u00e9viter que votre visiteur ne s&rsquo;en pose trop,&nbsp; -de questions- et sorte de votre site sans acheter ou vous contacter. \u00c7a s&rsquo;amplifie avec un saupoudrage d&rsquo;IA, une r\u00e9duction d&rsquo;insights bien frais, et &#8230; Un minimum de temps d\u00e9di\u00e9. Faut pas r\u00eaver, on n&rsquo;a rien sans rien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donc, si vous r\u00e9pondez \u00ab\u00a0&#8230; Heu &#8230; Pas une minute\u00a0\u00bb, ou \u00ab\u00a0peu de temps\u00a0\u00bb \u00e0 la question en intro de ce pitch de pr\u00e9sentation, venez, c&rsquo;est urgent, vous gaspillez votre \u00e9nergie SEO et acquisition de trafic, vous gaspillez vos visiteurs&#8230;&nbsp;\ud83d\ude09&nbsp;Et par les temps qui courent, le gaspillage &#8230; On essaie d&rsquo;\u00e9viter, non ?&nbsp;\ud83c\udf40<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En bref, la vraie question est : combien de points de conversion, c&rsquo;est \u00e0 dire de clients ou de leads,&nbsp; gagnerez-vous \u00e0 participer \u00e0 cette keynote de Fr\u00e9d\u00e9ric P\u00e9r\u00e8s, d\u00e9favorablement connu pour son obsession de la conversion des entonnoirs web.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous managez un site WordPress ecommerce ou g\u00e9n\u00e9rateur de lead ? Fort bien &#8230; Et combien de temps avez-vous consacr\u00e9, ce trimestre, \u00e0 l&rsquo;am\u00e9lioration de la conversion de votre site ? &#8230;&nbsp;\ud83d\ude33&nbsp;&#8230; Ok &#8230;&nbsp; On s&rsquo;en doutait &#8230; On en reparle plus bas La conversion sur un site, \u00e7a ne se r\u00eave pas,&nbsp; \u00e7a ne [&hellip;]<\/p>\n","protected":false},"author":388646,"featured_media":2599,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_wcpt_session_time":1696602600,"_wcpt_session_duration":3600,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[2269],"footnotes":""},"session_track":[25],"session_category":[],"class_list":["post-2267","wcb_session","type-wcb_session","status-publish","has-post-thumbnail","hentry","wcb_track-0-auditorium"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peI5BS-Az","session_date_time":{"date":"6 octobre 2023","time":"16h30"},"session_speakers":[{"id":"2269","slug":"frederic-peres","name":"Fr\u00e9d\u00e9ric P\u00e9r\u00e8s","link":"https:\/\/biarritz.wordcamp.org\/2023\/speaker\/frederic-peres\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/sessions\/2267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/types\/wcb_session"}],"author":[{"embeddable":true,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/users\/388646"}],"version-history":[{"count":3,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/sessions\/2267\/revisions"}],"predecessor-version":[{"id":2324,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/sessions\/2267\/revisions\/2324"}],"speakers":[{"embeddable":true,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/speakers\/2269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/media\/2599"}],"wp:attachment":[{"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/media?parent=2267"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/session_track?post=2267"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/biarritz.wordcamp.org\/2023\/wp-json\/wp\/v2\/session_category?post=2267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}